{"id":6310,"date":"2025-10-10T10:40:29","date_gmt":"2025-10-10T08:40:29","guid":{"rendered":"https:\/\/osv.osdorfer-sv.de\/?page_id=6310"},"modified":"2025-10-10T11:38:55","modified_gmt":"2025-10-10T09:38:55","slug":"osv-basketball","status":"publish","type":"page","link":"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/osv-basketball\/","title":{"rendered":"OSV &#8211; Basketball"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6310\" class=\"elementor elementor-6310\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ac267d she-header-yes elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"8ac267d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;transparent&quot;:&quot;yes&quot;,&quot;background_show&quot;:&quot;yes&quot;,&quot;background&quot;:&quot;#014001&quot;,&quot;jet_sticky_section_sticky&quot;:&quot;yes&quot;,&quot;jet_sticky_section_sticky_visibility&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;transparent_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;scroll_distance&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:60,&quot;sizes&quot;:[]},&quot;scroll_distance_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;scroll_distance_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;she_offset_top_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;she_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:0,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:0,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3afada\" data-id=\"a3afada\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d15817f wpr-main-menu-align-center wpr-pointer-none wpr-main-menu-align--tabletcenter wpr-mobile-menu-custom-width wpr-main-menu-align--mobileleft wpr-sub-icon-caret-down wpr-sub-menu-fx-fade wpr-nav-menu-bp-mobile wpr-mobile-menu-drdown-align-center wpr-mobile-menu-item-align-center wpr-mobile-toggle-v1 wpr-sub-divider-yes wpr-mobile-divider-yes elementor-widget elementor-widget-wpr-nav-menu\" data-id=\"d15817f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;menu_layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"wpr-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"wpr-nav-menu-container wpr-nav-menu-horizontal\" data-trigger=\"hover\" data-consider-header=\"\" data-scroll-speed=\"500\"><ul id=\"menu-1-d15817f\" class=\"wpr-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-89\"><a href=\"https:\/\/osv.osdorfer-sv.de\/\" class=\"wpr-menu-item wpr-pointer-item menu-link\">Startseite<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-90\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"#news\" class=\"wpr-menu-item wpr-pointer-item\">Aktuelles<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5096\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/vereinzeitung-2023-2024\/\" class=\"wpr-sub-menu-item menu-link\">Vereinszeitung 2023\/2024<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5958\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/vereinszeitung-2024-2025\/\" class=\"wpr-sub-menu-item menu-link\">Vereinszeitung 2024\/2025<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-91\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"#abteilungen\" class=\"wpr-menu-item wpr-pointer-item\">Abteilungen<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-424\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/\" class=\"wpr-sub-menu-item\">Fu\u00dfball<i class=\"wpr-sub-icon fas wpr-sub-icon-rotate\" aria-hidden=\"true\"><\/i><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1278\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-1-herren\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 1.Herren<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-611\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-1-frauen\/\" class=\"wpr-sub-menu-item menu-link\">SG N-B O \u2013 1. Frauen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3070\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-schinkel-osdorf-2-herren\/\" class=\"wpr-sub-menu-item menu-link\">SG Schinkel Osdorf \u2013 2. Herren<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1986\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-altliga\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 Altliga<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5549\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-a-jugend\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 A-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1985\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-b-jugend\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 B-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-425\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-c-jugend\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 C-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-610\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-d-jugend\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 D-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1250\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-e1-jugend\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 E-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5548\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-e-juniorinnen\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 F-Juniorinnen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1249\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-f-jugend\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 F-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1248\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-g-jugend\/\" class=\"wpr-sub-menu-item menu-link\">OSV \u2013 G-Jugend<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-833\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/\" class=\"wpr-sub-menu-item\">Handball<i class=\"wpr-sub-icon fas wpr-sub-icon-rotate\" aria-hidden=\"true\"><\/i><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3762\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-1-damen\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf 1. Damen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3761\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-2-damen\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf 2. Damen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3760\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-3-damen\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf 3. Damen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3759\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-b-jugend-weiblich\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf B-Jugend weiblich<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3758\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-c-jugend-weiblich\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf C-Jugend weiblich<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3757\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-d-jugend-weiblich\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf D-Jugend weiblich<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3756\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-e-jugend-weiblich\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf E-Jugend weiblich<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3755\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-maxis\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf Maxis<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3754\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-minis\/\" class=\"wpr-sub-menu-item menu-link\">HSG Gettorf Osdorf Minis<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-832\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/tischtennis\/\" class=\"wpr-sub-menu-item\">Tischtennis<i class=\"wpr-sub-icon fas wpr-sub-icon-rotate\" aria-hidden=\"true\"><\/i><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2410\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/tischtennis\/tischtennis-mannschaften\/\" class=\"wpr-sub-menu-item menu-link\">Tischtennis \u2013 Mannschaften<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2409\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/tischtennis\/tischtennis-training\/\" class=\"wpr-sub-menu-item menu-link\">Tischtennis \u2013 Training<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-831\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/tennis\/\" class=\"wpr-sub-menu-item menu-link\">Tennis<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1023\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/sportschuetzen\/\" class=\"wpr-sub-menu-item menu-link\">Sportsch\u00fctzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1022\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/\" class=\"wpr-sub-menu-item\">Turnen<i class=\"wpr-sub-icon fas wpr-sub-icon-rotate\" aria-hidden=\"true\"><\/i><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3212\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/aerobic\/\" class=\"wpr-sub-menu-item menu-link\">Aerobic<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3215\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/eltern-kind-turnen\/\" class=\"wpr-sub-menu-item menu-link\">Kinderturnen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3210\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/jedermannsportgruppe\/\" class=\"wpr-sub-menu-item menu-link\">Jedermannsportgruppe<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3214\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/kinderturnen\/\" class=\"wpr-sub-menu-item menu-link\">Ger\u00e4tturnen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1020\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/yoga\/\" class=\"wpr-sub-menu-item menu-link\">Yoga<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3211\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/zumba\/\" class=\"wpr-sub-menu-item menu-link\">Zumba<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1136\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/seniorensport\/\" class=\"wpr-sub-menu-item menu-link\">Seniorensport<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6324\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/osv-basketball\/\" class=\"wpr-sub-menu-item menu-link\">Basketball<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1134\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/vorstand\/\" class=\"wpr-menu-item wpr-pointer-item menu-link\">Vorstand<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-103\"><a href=\"#vereinsheim\" class=\"wpr-menu-item wpr-pointer-item menu-link\">Vereinsheim &#038; Grillh\u00fctte<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-106\"><a aria-haspopup=\"true\" aria-expanded=\"false\" href=\"#info\" class=\"wpr-menu-item wpr-pointer-item\">Information<i class=\"wpr-sub-icon fas\" aria-hidden=\"true\"><\/i><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4271\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/satzung\/\" class=\"wpr-sub-menu-item menu-link\">Satzung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2646\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/ansprechpartner\/\" class=\"wpr-sub-menu-item menu-link\">Ansprechpartner<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2609\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/downloads\/\" class=\"wpr-sub-menu-item menu-link\">Downloads<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2608\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/haeufige-fragen\/\" class=\"wpr-sub-menu-item menu-link\">H\u00e4ufige Fragen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2607\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/hallen-und-sportplatznutzung\/\" class=\"wpr-sub-menu-item menu-link\">Hallen und Sportplatznutzung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6052\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/osv-zeltverleih\/\" class=\"wpr-sub-menu-item menu-link\">OSV Zeltverleih<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav><nav class=\"wpr-mobile-nav-menu-container\"><div class=\"wpr-mobile-toggle-wrap\"><div class=\"wpr-mobile-toggle\"><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><\/div><\/div><ul id=\"mobile-menu-2-d15817f\" class=\"wpr-mobile-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-89\"><a href=\"https:\/\/osv.osdorfer-sv.de\/\" class=\"wpr-mobile-menu-item menu-link\">Startseite<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-90\"><a aria-expanded=\"false\" href=\"#news\" class=\"wpr-mobile-menu-item menu-link\">Aktuelles<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc umschalten\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5096\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/vereinzeitung-2023-2024\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Vereinszeitung 2023\/2024<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5958\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/vereinszeitung-2024-2025\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Vereinszeitung 2024\/2025<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-91\"><a aria-expanded=\"false\" href=\"#abteilungen\" class=\"wpr-mobile-menu-item menu-link\">Abteilungen<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc umschalten\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-424\"><a aria-expanded=\"false\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Fu\u00dfball<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc umschalten\" aria-haspopup=\"true\"><\/span><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1278\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-1-herren\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 1.Herren<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-611\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-1-frauen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">SG N-B O \u2013 1. Frauen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3070\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-schinkel-osdorf-2-herren\/\" class=\"wpr-mobile-sub-menu-item menu-link\">SG Schinkel Osdorf \u2013 2. Herren<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1986\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-altliga\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 Altliga<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5549\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-a-jugend\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 A-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1985\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-b-jugend\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 B-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-425\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-c-jugend\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 C-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-610\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-d-jugend\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 D-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1250\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-e1-jugend\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 E-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5548\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/sg-n-b-o-e-juniorinnen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 F-Juniorinnen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1249\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-f-jugend\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 F-Jugend<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1248\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/fussball\/osv-g-jugend\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV \u2013 G-Jugend<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-833\"><a aria-expanded=\"false\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Handball<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc umschalten\" aria-haspopup=\"true\"><\/span><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3762\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-1-damen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf 1. Damen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3761\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-2-damen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf 2. Damen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3760\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-3-damen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf 3. Damen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3759\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-b-jugend-weiblich\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf B-Jugend weiblich<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3758\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-c-jugend-weiblich\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf C-Jugend weiblich<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3757\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-d-jugend-weiblich\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf D-Jugend weiblich<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3756\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-e-jugend-weiblich\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf E-Jugend weiblich<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3755\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-maxis\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf Maxis<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3754\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/handball\/hsg-gettorf-osdorf-minis\/\" class=\"wpr-mobile-sub-menu-item menu-link\">HSG Gettorf Osdorf Minis<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-832\"><a aria-expanded=\"false\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/tischtennis\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Tischtennis<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc umschalten\" aria-haspopup=\"true\"><\/span><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2410\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/tischtennis\/tischtennis-mannschaften\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Tischtennis \u2013 Mannschaften<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2409\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/tischtennis\/tischtennis-training\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Tischtennis \u2013 Training<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-831\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/tennis\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Tennis<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1023\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/sportschuetzen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Sportsch\u00fctzen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1022\"><a aria-expanded=\"false\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Turnen<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc umschalten\" aria-haspopup=\"true\"><\/span><\/a>\n\t<ul class=\"sub-menu wpr-sub-menu\">\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3212\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/aerobic\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Aerobic<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3215\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/eltern-kind-turnen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Kinderturnen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3210\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/jedermannsportgruppe\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Jedermannsportgruppe<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3214\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/kinderturnen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Ger\u00e4tturnen<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1020\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/yoga\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Yoga<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3211\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/turnen\/zumba\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Zumba<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1136\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/seniorensport\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Seniorensport<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6324\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/osv-basketball\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Basketball<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1134\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/vorstand\/\" class=\"wpr-mobile-menu-item menu-link\">Vorstand<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-103\"><a href=\"#vereinsheim\" class=\"wpr-mobile-menu-item menu-link\">Vereinsheim &#038; Grillh\u00fctte<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-106\"><a aria-expanded=\"false\" href=\"#info\" class=\"wpr-mobile-menu-item menu-link\">Information<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc umschalten\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu wpr-sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4271\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/satzung\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Satzung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2646\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/ansprechpartner\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Ansprechpartner<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2609\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/downloads\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Downloads<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2608\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/haeufige-fragen\/\" class=\"wpr-mobile-sub-menu-item menu-link\">H\u00e4ufige Fragen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2607\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/hallen-und-sportplatznutzung\/\" class=\"wpr-mobile-sub-menu-item menu-link\">Hallen und Sportplatznutzung<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6052\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/osv-zeltverleih\/\" class=\"wpr-mobile-sub-menu-item menu-link\">OSV Zeltverleih<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac69553 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"ac69553\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5796e83\" data-id=\"5796e83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ee3a54 elementor-widget elementor-widget-spacer\" data-id=\"5ee3a54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63fc48d elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no elementor-invisible\" data-id=\"63fc48d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;slideInRight&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-65591cb\" data-id=\"65591cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8d7919 elementor-widget elementor-widget-image\" data-id=\"c8d7919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/elementor\/thumbs\/logo3-q4wjracy1lq3ed3trtvsysgdljorfwq9p7q4rhr20w.png\" title=\"logo3.png\" alt=\"logo3.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fbc0f6a\" data-id=\"fbc0f6a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e052ad elementor-widget elementor-widget-heading\" data-id=\"5e052ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">OSV - ein Verein f\u00fcr alle<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a318b20 elementor-widget elementor-widget-heading\" data-id=\"a318b20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OSV  Basketball<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c0448 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"b8c0448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><strong><span style=\"color: #ffffff;\">Team ist nicht nur ein Wort<\/span><\/strong><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42fefcb elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"42fefcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.fussball.de\/mannschaft\/osdorfer-sv-osdorfer-sv-schleswig-holstein\/-\/saison\/2223\/team-id\/011MI95K7O000000VTVG0001VTR8C1K7#!\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mannschaftsspielplan bei Fussball.de<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e94af22 elementor-widget elementor-widget-spacer\" data-id=\"e94af22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbbae8e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"dbbae8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"#trainer\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trainer &amp; Trainingszeiten<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ca0519 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"2ca0519\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e14e0f\" data-id=\"6e14e0f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c5bd350 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c5bd350\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2e10070\" data-id=\"2e10070\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a86986 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1a86986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c104bb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c104bb0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cf3b82\" data-id=\"4cf3b82\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3c6c816 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"3c6c816\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b3639b8\" data-id=\"b3639b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71aa23f wpr-grid-columns-3 wpr-grid-columns--tablet2 wpr-grid-columns--mobile1 wpr-grid-pagination-center wpr-item-styles-inner elementor-widget elementor-widget-wpr-grid\" data-id=\"71aa23f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"wpr-grid-filters elementor-clearfix wpr-grid-filters-sep-right\"><li class=\" wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-none\"><span   data-ajax-filter=[\"category\",\"allgemein\"]  data-filter=\".category-allgemein\">Allgemein<\/span><em class=\"wpr-grid-filters-sep\"><\/em><\/li><\/ul><section class=\"wpr-grid elementor-clearfix\" data-settings=\"{&quot;layout&quot;:&quot;fitRows&quot;,&quot;stick_last_element_to_bottom&quot;:&quot;&quot;,&quot;columns_desktop&quot;:3,&quot;gutter_hr&quot;:15,&quot;gutter_hr_mobile&quot;:15,&quot;gutter_hr_mobile_extra&quot;:15,&quot;gutter_hr_tablet&quot;:15,&quot;gutter_hr_tablet_extra&quot;:15,&quot;gutter_hr_laptop&quot;:15,&quot;gutter_hr_widescreen&quot;:15,&quot;gutter_vr&quot;:15,&quot;gutter_vr_mobile&quot;:15,&quot;gutter_vr_mobile_extra&quot;:15,&quot;gutter_vr_tablet&quot;:15,&quot;gutter_vr_tablet_extra&quot;:15,&quot;gutter_vr_laptop&quot;:15,&quot;gutter_vr_widescreen&quot;:15,&quot;animation&quot;:&quot;zoom&quot;,&quot;animation_duration&quot;:0.3,&quot;animation_delay&quot;:0.1,&quot;deeplinking&quot;:&quot;&quot;,&quot;filters_linkable&quot;:&quot;&quot;,&quot;filters_default_filter&quot;:&quot;&quot;,&quot;filters_count&quot;:&quot;&quot;,&quot;filters_hide_empty&quot;:&quot;no&quot;,&quot;filters_animation&quot;:&quot;default&quot;,&quot;filters_animation_duration&quot;:0.3,&quot;filters_animation_delay&quot;:0.1,&quot;pagination_type&quot;:&quot;load-more&quot;,&quot;pagination_max_pages&quot;:2,&quot;lightbox&quot;:{&quot;selector&quot;:&quot;.wpr-grid-image-wrap&quot;,&quot;iframeMaxWidth&quot;:&quot;60%&quot;,&quot;hash&quot;:false,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause&quot;:5000,&quot;progressBar&quot;:&quot;true&quot;,&quot;counter&quot;:&quot;true&quot;,&quot;controls&quot;:&quot;true&quot;,&quot;getCaptionFromTitleOrAlt&quot;:&quot;true&quot;,&quot;thumbnail&quot;:&quot;&quot;,&quot;showThumbByDefault&quot;:&quot;&quot;,&quot;share&quot;:&quot;&quot;,&quot;zoom&quot;:&quot;true&quot;,&quot;fullScreen&quot;:&quot;true&quot;,&quot;download&quot;:&quot;true&quot;}}\" data-advanced-filters=\"no\"><article class=\"wpr-grid-item elementor-clearfix post-6579 post type-post status-publish format-standard has-post-thumbnail hentry category-aktuelles category-allgemein category-tischtennis\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium \" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2026\/04\/Plakat-Familientraining_deckel.jpg\" data-img-on-hover=\"\"  data-src-secondary=\"\"><img decoding=\"async\" data-no-lazy=\"1\" src=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2026\/04\/Plakat-Familientraining_deckel.jpg\" alt=\"Familientraining\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2026\/04\/10\/familientraining-2\/\"><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><h2 class=\"wpr-grid-item-title elementor-repeater-item-f7818f2 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"  href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2026\/04\/10\/familientraining-2\/\">Familientraining<\/a><\/div><\/h2><div class=\"wpr-grid-item-date elementor-repeater-item-a786cbf wpr-grid-item-display-inline wpr-grid-item-align-left\"><div class=\"inner-block\"><span>10. April 2026<span class=\"wpr-grid-extra-text-right\"><\/span><\/span><\/div><\/div><div class=\"wpr-grid-item-excerpt elementor-repeater-item-b62c71d wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><p>Tischtennis Familientraining<\/p><\/div><\/div><div class=\"wpr-grid-item-read-more elementor-repeater-item-6739d65 wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><a target=\"_self\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2026\/04\/10\/familientraining-2\/\" class=\"wpr-button-effect wpr-button-none\"><span>weiter...<\/span><\/a><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-6385 post type-post status-publish format-standard has-post-thumbnail hentry category-aktuelles category-allgemein category-tischtennis\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium \" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2026\/02\/fe55565d-3150-4db7-bea6-962dc28ee8f7.jpg\" data-img-on-hover=\"\"  data-src-secondary=\"\"><img decoding=\"async\" data-no-lazy=\"1\" src=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2026\/02\/fe55565d-3150-4db7-bea6-962dc28ee8f7.jpg\" alt=\"Tischtennisturnier 2026\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2026\/02\/13\/tischtennisturnier-2026\/\"><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><h2 class=\"wpr-grid-item-title elementor-repeater-item-f7818f2 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"  href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2026\/02\/13\/tischtennisturnier-2026\/\">Tischtennisturnier 2026<\/a><\/div><\/h2><div class=\"wpr-grid-item-date elementor-repeater-item-a786cbf wpr-grid-item-display-inline wpr-grid-item-align-left\"><div class=\"inner-block\"><span>13. Februar 2026<span class=\"wpr-grid-extra-text-right\"><\/span><\/span><\/div><\/div><div class=\"wpr-grid-item-excerpt elementor-repeater-item-b62c71d wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><p>Tischtennisturnier 2026 &quot;Wir bitten zu Tisch&quot; oder &quot;Weg mit dem Weihnachtsspeck&quot;<\/p><\/div><\/div><div class=\"wpr-grid-item-read-more elementor-repeater-item-6739d65 wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><a target=\"_self\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2026\/02\/13\/tischtennisturnier-2026\/\" class=\"wpr-button-effect wpr-button-none\"><span>weiter...<\/span><\/a><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-6081 post type-post status-publish format-standard has-post-thumbnail hentry category-aktuelles category-allgemein category-fussball tag-a-jugend tag-b-jugend tag-c-jugend tag-d-jugend tag-e-jugend tag-e-juniorinnen tag-f-jugend tag-f-juniorinnen tag-fussball tag-g-jugend\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium \" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2025\/06\/werbung-Spieler2025.jpg\" data-img-on-hover=\"\"  data-src-secondary=\"\"><img decoding=\"async\" data-no-lazy=\"1\" src=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2025\/06\/werbung-Spieler2025.jpg\" alt=\"Neue Junioren 2025\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2025\/06\/19\/neue-junioren-2025\/\"><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><h2 class=\"wpr-grid-item-title elementor-repeater-item-f7818f2 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"  href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2025\/06\/19\/neue-junioren-2025\/\">Neue Junioren 2025<\/a><\/div><\/h2><div class=\"wpr-grid-item-date elementor-repeater-item-a786cbf wpr-grid-item-display-inline wpr-grid-item-align-left\"><div class=\"inner-block\"><span>19. Juni 2025<span class=\"wpr-grid-extra-text-right\"><\/span><\/span><\/div><\/div><div class=\"wpr-grid-item-excerpt elementor-repeater-item-b62c71d wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><p>Nachdem unsere Jugendfu\u00dfballabteilung endlich wieder in jeder Altersklasse von G-Jugend bis A-Jugend aufgestellt ist, m\u00f6chten wir den n\u00e4chsten Schritt gehen....<\/p><\/div><\/div><div class=\"wpr-grid-item-read-more elementor-repeater-item-6739d65 wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><a target=\"_self\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/2025\/06\/19\/neue-junioren-2025\/\" class=\"wpr-button-effect wpr-button-none\"><span>weiter...<\/span><\/a><\/div><\/div><\/div><\/div><\/article><\/section><div class=\"wpr-grid-pagination elementor-clearfix wpr-grid-pagination-load-more\" data-pages=\"2\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/pages\/6310\/page\/2\/\" class=\"wpr-load-more-btn\" data-e-disable-page-transition >\u00e4ltere Beitr\u00e4ge<\/a><div class=\"wpr-pagination-loading\"><div class=\"wpr-double-bounce\"><div class=\"wpr-child wpr-double-bounce1\"><\/div><div class=\"wpr-child wpr-double-bounce2\"><\/div><\/div><\/div><p class=\"wpr-pagination-finish\">End of Content.<\/p><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d2f3390 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"d2f3390\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c97d44a\" data-id=\"c97d44a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-469c74b elementor-widget elementor-widget-heading\" data-id=\"469c74b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OSV - - -  Basketball<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1573c73 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"1573c73\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bd5c89d\" data-id=\"bd5c89d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb88dca elementor-widget elementor-widget-image\" data-id=\"fb88dca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"987\" src=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2025\/10\/image0-1024x987.jpeg\" class=\"attachment-large size-large wp-image-6316\" alt=\"\" srcset=\"https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2025\/10\/image0-1024x987.jpeg 1024w, https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2025\/10\/image0-300x289.jpeg 300w, https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2025\/10\/image0-768x740.jpeg 768w, https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2025\/10\/image0-1536x1480.jpeg 1536w, https:\/\/osv.osdorfer-sv.de\/wp-content\/uploads\/2025\/10\/image0-2048x1974.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-299551a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"299551a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0021b83\" data-id=\"0021b83\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9a71876 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"9a71876\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1089311\" data-id=\"1089311\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e49e6ed elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e49e6ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88c342d elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"88c342d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dd32633\" data-id=\"dd32633\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fa3cc5 elementor-widget elementor-widget-text-editor\" data-id=\"7fa3cc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Die Basketballer trainieren Montags von <\/span><br \/><span style=\"color: #ffffff;\">20:30 Uhr bis 22:00 Uhr in der Sporthalle Osdorf<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-33c829c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"33c829c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-795f9fc\" data-id=\"795f9fc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d560033 elementor-widget elementor-widget-text-editor\" data-id=\"d560033\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\">\u00a0<\/span><\/h2><h3 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Ansprechpartner: Felix Tr\u00fcmpelmann mobil: 0160 97943198<\/span><\/h3><h3 style=\"text-align: center;\">\u00a0<\/h3><div><span style=\"color: #ffffff;\">\u00a0<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7510172 elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"7510172\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e30a5f4\" data-id=\"e30a5f4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c26952a elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"c26952a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-19de027\" data-id=\"19de027\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-810e32b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"810e32b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a5c496 wpr-main-menu-align-center wpr-pointer-none wpr-main-menu-align--tabletleft wpr-main-menu-align--mobileleft wpr-sub-icon-caret-down wpr-sub-menu-fx-fade wpr-nav-menu-bp-mobile wpr-mobile-menu-full-width wpr-mobile-menu-item-align-center wpr-mobile-toggle-v1 wpr-sub-divider-yes wpr-mobile-divider-yes elementor-widget elementor-widget-wpr-nav-menu\" data-id=\"2a5c496\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;menu_layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"wpr-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"wpr-nav-menu-container wpr-nav-menu-horizontal\" data-trigger=\"hover\" data-consider-header=\"\" data-scroll-speed=\"500\"><ul id=\"menu-1-2a5c496\" class=\"wpr-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3921\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/impressum\/\" class=\"wpr-menu-item wpr-pointer-item menu-link\">Impressum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-privacy-policy menu-item-3922\"><a rel=\"privacy-policy\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/datenschutzerklaerung\/\" class=\"wpr-menu-item wpr-pointer-item menu-link\">Datenschutzerkl\u00e4rung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4492\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/cookie-richtlinie-eu\/\" class=\"wpr-menu-item wpr-pointer-item menu-link\">Cookie-Richtlinie (EU)<\/a><\/li>\n<\/ul><\/nav><nav class=\"wpr-mobile-nav-menu-container\"><div class=\"wpr-mobile-toggle-wrap\"><div class=\"wpr-mobile-toggle\"><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><\/div><\/div><ul id=\"mobile-menu-2-2a5c496\" class=\"wpr-mobile-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3921\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/impressum\/\" class=\"wpr-mobile-menu-item menu-link\">Impressum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-privacy-policy menu-item-3922\"><a rel=\"privacy-policy\" href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/datenschutzerklaerung\/\" class=\"wpr-mobile-menu-item menu-link\">Datenschutzerkl\u00e4rung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4492\"><a href=\"https:\/\/osv.osdorfer-sv.de\/index.php\/startseite\/cookie-richtlinie-eu\/\" class=\"wpr-mobile-menu-item menu-link\">Cookie-Richtlinie (EU)<\/a><\/li>\n<\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Startseite Aktuelles Vereinszeitung 2023\/2024 Vereinszeitung 2024\/2025 Abteilungen Fu\u00dfball OSV \u2013 1.Herren SG N-B O \u2013 1. Frauen SG Schinkel Osdorf \u2013 2. Herren OSV \u2013 Altliga OSV \u2013 A-Jugend OSV \u2013 B-Jugend OSV \u2013 C-Jugend OSV \u2013 D-Jugend OSV \u2013 E-Jugend OSV \u2013 F-Juniorinnen OSV \u2013 F-Jugend OSV \u2013 G-Jugend Handball HSG Gettorf Osdorf 1. Damen HSG Gettorf Osdorf 2. Damen HSG Gettorf Osdorf 3. Damen HSG Gettorf Osdorf B-Jugend weiblich HSG Gettorf Osdorf C-Jugend weiblich HSG Gettorf Osdorf D-Jugend weiblich HSG Gettorf Osdorf E-Jugend weiblich HSG Gettorf Osdorf Maxis HSG Gettorf Osdorf Minis Tischtennis Tischtennis \u2013 Mannschaften Tischtennis \u2013 Training Tennis Sportsch\u00fctzen Turnen Aerobic Kinderturnen Jedermannsportgruppe Ger\u00e4tturnen Yoga Zumba Seniorensport Vorstand Vereinsheim &#038; Grillh\u00fctte Information Satzung Ansprechpartner Downloads H\u00e4ufige Fragen Hallen und Sportplatznutzung OSV Zeltverleih Startseite Aktuelles Vereinszeitung 2023\/2024 Vereinszeitung 2024\/2025 Abteilungen Fu\u00dfball OSV \u2013 1.Herren SG N-B O \u2013 1. Frauen SG Schinkel Osdorf \u2013 2. Herren OSV \u2013 Altliga OSV \u2013 A-Jugend OSV \u2013 B-Jugend OSV \u2013 C-Jugend OSV \u2013 D-Jugend OSV \u2013 E-Jugend OSV \u2013 F-Juniorinnen OSV \u2013 F-Jugend OSV \u2013 G-Jugend Handball HSG Gettorf Osdorf 1. Damen HSG Gettorf Osdorf 2. Damen HSG Gettorf Osdorf 3. Damen HSG Gettorf Osdorf B-Jugend weiblich HSG Gettorf Osdorf C-Jugend weiblich HSG Gettorf Osdorf D-Jugend weiblich HSG Gettorf Osdorf E-Jugend weiblich HSG Gettorf Osdorf Maxis HSG Gettorf Osdorf Minis Tischtennis Tischtennis \u2013 Mannschaften Tischtennis \u2013 Training Tennis Sportsch\u00fctzen Turnen Aerobic Kinderturnen Jedermannsportgruppe Ger\u00e4tturnen Yoga Zumba Seniorensport Vorstand Vereinsheim &#038; Grillh\u00fctte Information Satzung Ansprechpartner Downloads H\u00e4ufige Fragen Hallen und Sportplatznutzung OSV Zeltverleih OSV &#8211; ein Verein f\u00fcr alle OSV Basketball Team ist nicht nur ein Wort Mannschaftsspielplan bei Fussball.de Trainer &amp; Trainingszeiten Allgemein Neue Junioren 2025 19. Juni 2025 Nachdem unsere Jugendfu\u00dfballabteilung endlich wieder in jeder Altersklasse von G-Jugend bis A-Jugend aufgestellt ist, m\u00f6chten wir den n\u00e4chsten Schritt gehen&#8230;. weiter&#8230; Osdorfer Fu\u00dfballjuniorinnen &#8211; wir suchen dich &#8211; 19. Juni 2025 Nachdem unsere Jugendfu\u00dfballabteilung endlich wieder in jeder Altersklasse von G-Jugend bis A-Jugend aufgestellt ist, m\u00f6chten wir den n\u00e4chsten Schritt gehen&#8230;. weiter&#8230; Zeltverleih f\u00fcr OSV Mitglieder 2. Juni 2025 Das OSV Zelt (Gr\u00f6\u00dfe 4 x 8 m) kann ab sofort von Mitgliedern f\u00fcr einen Betrag von 50 \u20ac (3-4&#8230; weiter&#8230; \u00e4ltere Beitr\u00e4ge End of Content. OSV &#8211; &#8211; &#8211; Basketball Die Basketballer trainieren Montags von 20:30 Uhr bis 22:00 Uhr in der Sporthalle Osdorf \u00a0 Ansprechpartner: Felix Tr\u00fcmpelmann mobil: 0160 97943198 \u00a0 \u00a0 Impressum Datenschutzerkl\u00e4rung Cookie-Richtlinie (EU) Impressum Datenschutzerkl\u00e4rung Cookie-Richtlinie (EU)<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":9,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6310","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/pages\/6310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/comments?post=6310"}],"version-history":[{"count":10,"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/pages\/6310\/revisions"}],"predecessor-version":[{"id":6323,"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/pages\/6310\/revisions\/6323"}],"up":[{"embeddable":true,"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/pages\/9"}],"wp:attachment":[{"href":"https:\/\/osv.osdorfer-sv.de\/index.php\/wp-json\/wp\/v2\/media?parent=6310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}